{"id":3599,"date":"2020-01-26T15:56:54","date_gmt":"2020-01-26T15:56:54","guid":{"rendered":"https:\/\/www.cmelaciplus.cz\/?page_id=3599"},"modified":"2024-03-08T16:28:13","modified_gmt":"2024-03-08T16:28:13","slug":"beobachtungsfenster-ulu","status":"publish","type":"page","link":"https:\/\/www.cmelaciplus.cz\/de\/pozorovaci-okenko-ulu\/","title":{"rendered":"Beobachtungsfenster des Bienenstocks"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3599\" class=\"elementor elementor-3599\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cfae83d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cfae83d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-656034f6\" data-id=\"656034f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75b19579 elementor-widget elementor-widget-heading\" data-id=\"75b19579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie man Hummeln in ihrem Nest beobachtet\nDas Beobachtungsfenster und seine Verwendung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-276de2ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"276de2ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74894a8e\" data-id=\"74894a8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6288eefc elementor-widget elementor-widget-spacer\" data-id=\"6288eefc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36529ba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36529ba8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b177504\" data-id=\"3b177504\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-956539d elementor-nav-menu--dropdown-mobile elementor-nav-menu__align-start elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-global elementor-global-33299 elementor-widget-nav-menu\" data-id=\"956539d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-956539d\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-799\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/rad-bych-zacal-chovat-cmelaky\/\" class=\"elementor-item\">Ich m\u00f6chte mit der Haltung von Hummeln beginnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-prvni-uvaha\/\" class=\"elementor-item\">Die notwendige erste \u00dcberlegung<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3766\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-ziskat-cmelaky\/\" class=\"elementor-item\">Wie man Hummeln bekommt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-802\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vybrat-spravny-ul\/\" class=\"elementor-item\">Wie w\u00e4hlt man den richtigen Turm aus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38041\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-vybava-ulu\/\" class=\"elementor-item\">Notwendige Bienenstockausstattung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-805\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/chodba-v-ulu\/\" class=\"elementor-sub-item\">Gang in der Bienenstock<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-806\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vetrani\/\" class=\"elementor-sub-item\">Bienenstockentl\u00fcftung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka\/\" class=\"elementor-sub-item\">Klapka<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-5373\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka-zvedani-zaklopky\/\" class=\"elementor-sub-item\">L\u00f6sung zum Anheben des Klappenschlosses<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2892\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/strecha-cmelaciho-ulu\/\" class=\"elementor-sub-item\">Dach des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25831\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/tepelna-izolace-a-vytapeni-ulku-pro-cmelaky\/\" class=\"elementor-sub-item\">W\u00e4rmed\u00e4mmung und Heizung von Beuten<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3606\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-vytah-k-bezpecne-kontrole-hnizd\/\" class=\"elementor-sub-item\">Hummelaufzug f\u00fcr sichere Eingriffe ins Nest<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vystelka\/\" class=\"elementor-sub-item\">Auskleidung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3607\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pozorovaci-okenko-ulu\/\" class=\"elementor-sub-item\">Guckloch des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38137\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">======================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-chovatele-cmelaku\/\" class=\"elementor-item\">Z\u00fcchterhilfen<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37248\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-odchyt-a-usazeni-kralovny\/\" class=\"elementor-sub-item\">Hilfsmittel zum Fangen und Einsetzen der K\u00f6nigin<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37247\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-bezpecnou-kontrolu-v-ulku\/\" class=\"elementor-sub-item\">Hilfsmittel f\u00fcr die sichere Kontrolle des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38138\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">=================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37249\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/krmeni-krmitka-prikrmovani-cmelaku\/\" class=\"elementor-item\">F\u00fctterung und Zuf\u00fctterung von Hummeln<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-893\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kudy-cesta-nevede\/\" class=\"elementor-item\">GEF\u00c4HRLICHE Dinge f\u00fcr Hummeln<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8405\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodne-komercne-dostupne-ulky\/\" class=\"elementor-sub-item\">Ungeeignete im Handel erh\u00e4ltliche Rohlinge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30192\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nebezpecne-pripravky-proti-parazitum\/\" class=\"elementor-sub-item\">Gef\u00e4hrliche Parasitenbek\u00e4mpfungsmittel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5884\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prodej-nepuvodnich-druhu-cmelaku\/\" class=\"elementor-sub-item\">Verkauf von nicht-einheimischen Hybriden von Nutzpflanzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5843\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodna-odchytova-sada\/\" class=\"elementor-sub-item\">Ungeeignetes Fangset<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30193\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\">Bacillus thuringiensis: Risiko oder Nutzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38139\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">============================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38090\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pripravna-faze-chovu-cmelaku-v-ulku\/\" class=\"elementor-item\">Vorbereitungsphase der Zucht<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33503\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/priprava-ulku-pred-sezonou\/\" class=\"elementor-sub-item\">Vorbereitung des Magens vor der Saison<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26457\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2854\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\">Ameisen und der Schutz des Bienenstocks vor ihnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26750\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\">Wundermittel zum Schutz?<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nejcastejsi-chyby\/\" class=\"elementor-sub-item\">Die h\u00e4ufigsten Fehler<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-813\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu\/\" class=\"elementor-sub-item\">Auswahl Ihrer Anfragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38134\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===========================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38109\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-sezona-zacina\/\" class=\"elementor-item\">Die Hummel-Saison beginnt<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author nmr-logged-in menu-item menu-item-type-post_type menu-item-object-page menu-item-2463\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prvni-krok-nez-zahajite-sezonu\/\" class=\"elementor-sub-item\">Erste Schritte, bevor Sie die Saison beginnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26458\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33532\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umisteni-ulu-na-zahrade\/\" class=\"elementor-sub-item\">Wo platziere ich die Beute richtig<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4692\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-hleda-hnizdiste\/\" class=\"elementor-sub-item\">Mutter sucht Brutplatz<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-815\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-usadit-kralovnu-do-ulku\/\" class=\"elementor-sub-item\">Wie man eine Hummel in einen Bienenstock setzt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36889\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/atraktant-pro-obsazeni-ulku-s-cmelaky\/\" class=\"elementor-sub-item\">Lockstoff f\u00fcr Hummelnestbesiedlung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-797\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/mam-nebo-nemam-usazeno\/\" class=\"elementor-sub-item\">Habe ich oder habe ich nicht sesshaft geworden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5983\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-se-usadila-v-hnizdisti\/\" class=\"elementor-sub-item\">Die Mutter lie\u00df sich im Nest nieder<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-796\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umeni-klapky\/\" class=\"elementor-sub-item\">Die Kunst des Klappens<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-795\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/extremni-vlivy-jara-mraziky\/\" class=\"elementor-sub-item\">Extremwetter im Fr\u00fchling: Frost<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6940\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-a-jak-vetrat-ulek\/\" class=\"elementor-sub-item\">Wann und wie man eine Bienenstockkiste mit Hummeln l\u00fcftet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38136\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===============================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33573\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-hnizdo-v-dobe-delnic\/\" class=\"elementor-item\">Einzelne Phase der Mutter und der ersten Arbeiterinnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7049\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kontroly-hnizda-v-ulku\/\" class=\"elementor-item\">Pflege eines ausgebauten Wabenfunds im Bienenstock<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38115\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/parazite-a-predatori-ve-cmelacim-ulu\/\" class=\"elementor-item\">Parasiten und Raubtiere im Bienenstock<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pacmelaci-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Hummeln und Hummelzucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6786\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zavijec-cizopasny-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Zav\u00edje\u010d cizopasn\u00fd Aphomia sociella und Zucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18210\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/melittobia-acasta-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Melittobia acasta ein chov<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6709\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\">Ameisen und deren Bek\u00e4mpfung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38140\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32968\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Ende der Hummelkolonie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prohlidka-ulu-a-hnizda-na-konci-sezony\/\" class=\"elementor-sub-item\">Inspektion des Bienenstocks und des Nestes am Ende der Saison<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-850\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vycistit-a-zazimovat-ul\/\" class=\"elementor-sub-item\">Wie man einen Bienenstock reinigt und \u00fcberwintert<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-793\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu-2\/\" class=\"elementor-item\">Auswahl Ihrer Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-894\"><a href=\"http:\/\/www.cmelaciplus.cz\/de\/\" class=\"elementor-item\">Zur\u00fcck zum Anfang<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-956539d\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-799\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/rad-bych-zacal-chovat-cmelaky\/\" class=\"elementor-item\" tabindex=\"-1\">Ich m\u00f6chte mit der Haltung von Hummeln beginnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-prvni-uvaha\/\" class=\"elementor-item\" tabindex=\"-1\">Die notwendige erste \u00dcberlegung<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3766\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-ziskat-cmelaky\/\" class=\"elementor-item\" tabindex=\"-1\">Wie man Hummeln bekommt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-802\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vybrat-spravny-ul\/\" class=\"elementor-item\" tabindex=\"-1\">Wie w\u00e4hlt man den richtigen Turm aus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38041\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-vybava-ulu\/\" class=\"elementor-item\" tabindex=\"-1\">Notwendige Bienenstockausstattung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-805\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/chodba-v-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gang in der Bienenstock<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-806\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vetrani\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bienenstockentl\u00fcftung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Klapka<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-5373\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka-zvedani-zaklopky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">L\u00f6sung zum Anheben des Klappenschlosses<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2892\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/strecha-cmelaciho-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Dach des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25831\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/tepelna-izolace-a-vytapeni-ulku-pro-cmelaky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">W\u00e4rmed\u00e4mmung und Heizung von Beuten<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3606\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-vytah-k-bezpecne-kontrole-hnizd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hummelaufzug f\u00fcr sichere Eingriffe ins Nest<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vystelka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Auskleidung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3607\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pozorovaci-okenko-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Guckloch des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38137\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">======================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-chovatele-cmelaku\/\" class=\"elementor-item\" tabindex=\"-1\">Z\u00fcchterhilfen<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37248\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-odchyt-a-usazeni-kralovny\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hilfsmittel zum Fangen und Einsetzen der K\u00f6nigin<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37247\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-bezpecnou-kontrolu-v-ulku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hilfsmittel f\u00fcr die sichere Kontrolle des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38138\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">=================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37249\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/krmeni-krmitka-prikrmovani-cmelaku\/\" class=\"elementor-item\" tabindex=\"-1\">F\u00fctterung und Zuf\u00fctterung von Hummeln<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-893\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kudy-cesta-nevede\/\" class=\"elementor-item\" tabindex=\"-1\">GEF\u00c4HRLICHE Dinge f\u00fcr Hummeln<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8405\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodne-komercne-dostupne-ulky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ungeeignete im Handel erh\u00e4ltliche Rohlinge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30192\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nebezpecne-pripravky-proti-parazitum\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gef\u00e4hrliche Parasitenbek\u00e4mpfungsmittel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5884\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prodej-nepuvodnich-druhu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Verkauf von nicht-einheimischen Hybriden von Nutzpflanzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5843\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodna-odchytova-sada\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ungeeignetes Fangset<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30193\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bacillus thuringiensis: Risiko oder Nutzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38139\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">============================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38090\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pripravna-faze-chovu-cmelaku-v-ulku\/\" class=\"elementor-item\" tabindex=\"-1\">Vorbereitungsphase der Zucht<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33503\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/priprava-ulku-pred-sezonou\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vorbereitung des Magens vor der Saison<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26457\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2854\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ameisen und der Schutz des Bienenstocks vor ihnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26750\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wundermittel zum Schutz?<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nejcastejsi-chyby\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die h\u00e4ufigsten Fehler<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-813\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Auswahl Ihrer Anfragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38134\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===========================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38109\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-sezona-zacina\/\" class=\"elementor-item\" tabindex=\"-1\">Die Hummel-Saison beginnt<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author nmr-logged-in menu-item menu-item-type-post_type menu-item-object-page menu-item-2463\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prvni-krok-nez-zahajite-sezonu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Erste Schritte, bevor Sie die Saison beginnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26458\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33532\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umisteni-ulu-na-zahrade\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wo platziere ich die Beute richtig<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4692\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-hleda-hnizdiste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mutter sucht Brutplatz<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-815\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-usadit-kralovnu-do-ulku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wie man eine Hummel in einen Bienenstock setzt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36889\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/atraktant-pro-obsazeni-ulku-s-cmelaky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lockstoff f\u00fcr Hummelnestbesiedlung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-797\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/mam-nebo-nemam-usazeno\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Habe ich oder habe ich nicht sesshaft geworden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5983\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-se-usadila-v-hnizdisti\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die Mutter lie\u00df sich im Nest nieder<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-796\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umeni-klapky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die Kunst des Klappens<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-795\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/extremni-vlivy-jara-mraziky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Extremwetter im Fr\u00fchling: Frost<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6940\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-a-jak-vetrat-ulek\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann und wie man eine Bienenstockkiste mit Hummeln l\u00fcftet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38136\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===============================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33573\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-hnizdo-v-dobe-delnic\/\" class=\"elementor-item\" tabindex=\"-1\">Einzelne Phase der Mutter und der ersten Arbeiterinnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7049\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kontroly-hnizda-v-ulku\/\" class=\"elementor-item\" tabindex=\"-1\">Pflege eines ausgebauten Wabenfunds im Bienenstock<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38115\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/parazite-a-predatori-ve-cmelacim-ulu\/\" class=\"elementor-item\" tabindex=\"-1\">Parasiten und Raubtiere im Bienenstock<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pacmelaci-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hummeln und Hummelzucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6786\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zavijec-cizopasny-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Zav\u00edje\u010d cizopasn\u00fd Aphomia sociella und Zucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18210\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/melittobia-acasta-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Melittobia acasta ein chov<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6709\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ameisen und deren Bek\u00e4mpfung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38140\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32968\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Ende der Hummelkolonie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prohlidka-ulu-a-hnizda-na-konci-sezony\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Inspektion des Bienenstocks und des Nestes am Ende der Saison<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-850\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vycistit-a-zazimovat-ul\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wie man einen Bienenstock reinigt und \u00fcberwintert<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-793\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu-2\/\" class=\"elementor-item\" tabindex=\"-1\">Auswahl Ihrer Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-894\"><a href=\"http:\/\/www.cmelaciplus.cz\/de\/\" class=\"elementor-item\" tabindex=\"-1\">Zur\u00fcck zum Anfang<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-599b0ce7\" data-id=\"599b0ce7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-291e3e5c elementor-widget elementor-widget-text-editor\" data-id=\"291e3e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>\u00dcber das Beobachtungsfenster im Hummelnest (Bienenstock)<\/strong><\/h4><p>Alle sind daran interessiert, wie Hummeln im Bienenstock leben und wollen hineinschauen und beobachten, wie es in diesem Nest wirklich zugeht.<\/p><p>Wenn ein Bienenstock ge\u00f6ffnet wird, betrachten Hummeln das Licht im Stock als Besch\u00e4digung der Nistkammer oder als Angriff auf das Nest = sie erscheinen an der Oberfl\u00e4che der Auskleidung. Die Arbeiterinnen beginnen, die Auskleidung zu bearbeiten und versuchen instinktiv, das Nest zu bedecken. Aggressivere Arbeiterinnen fliegen aus dem Stock und verteidigen ihn.<\/p><p>Daher ist es gut, das Leben im Bienenstock durch Glas\/Plexiglas zu beobachten, mit dem Sie den offenen Bienenstock abdecken. Hummeln fliegen nicht heraus und Sie k\u00f6nnen sie in Ruhe beobachten.<\/p><p>In der Literatur \u00fcber Hummeln wird eine solche Beobachtung erw\u00e4hnt. Manche Hersteller verkaufen Ihnen zu ihren Nestern ein Beobachtungsfenster aus Plexiglas.<\/p><p>Man liest irgendwo, dass wenn der Schreck unter einem solchen Beobachtungsfenster langfristig abgedeckt ist, sich Feuchtigkeit aus dem Nest darauf absetzen kann und dadurch Schimmel entstehen kann. Das kann bei einem starken, gro\u00dfen Nest passieren.<\/p><p>Nirgendwo liest man aber, wie man ein solches Sichtfenster anbringt und wieder entfernt und auch nicht, dass das keine Wissenschaft ist.<br \/>Viele Anf\u00e4nger f\u00fcrchten sich vor dem Umgang mit Hummeln und lassen deshalb die Beobachtungsglasscheibe im Nest. Sie wundern sich oft, warum das Nest dann so feucht ist...<\/p><div id=\"attachment_3621\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-3621\" class=\"wp-image-3621 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-300x169.jpg\" alt=\"Hummel PLUS \u2013 Beobachtungsfenster aus Polycarbonat oben auf dem Bienenstock\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3621\" class=\"wp-caption-text\">Guckloch \u2013 auf dem Beutenabdeckung platziert<br \/>Foto O. Hercog<\/p><\/div><p>Hersteller empfehlen, das Deckglas auf Leisten zu legen, die Sie vor der Saison mit kleinen Schrauben\/N\u00e4geln am Bienenstock befestigen. Sie legen das Beobachtungsglas auf die Leisten. Dies kann jedoch nicht herausgenommen werden, ohne eine \u00d6se\/einen Haken\/ein Loch daran anzubringen.<\/p><p>Diese L\u00f6sung sieht gut aus, aber <strong>Wenn Sie das Beobachtungsfenster nicht auf einen Hummelkasten anbringen und dann wieder entfernen k\u00f6nnen, empfehlen wir dessen Verwendung nicht<\/strong>.\u00a0<\/p><div id=\"attachment_3626\" style=\"width: 313px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3626\" class=\"wp-image-3626\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_pridavne-okenko-k_ulku_cmelinu-300x200.jpg\" alt=\"Hummel PLUS - Einlege-Zusatzfenster f\u00fcr den Hummelstock\" width=\"303\" height=\"202\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_pridavne-okenko-k_ulku_cmelinu-300x200.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_pridavne-okenko-k_ulku_cmelinu-768x512.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_pridavne-okenko-k_ulku_cmelinu.jpg 794w\" sizes=\"(max-width: 303px) 100vw, 303px\" \/><p id=\"caption-attachment-3626\" class=\"wp-caption-text\">Einsatz-Zusatzfach f\u00fcr Bienenstock \u2013 eingesetzt in den Stock<br \/>Foto Web-H\u00e4ndler<\/p><\/div><p><strong>\u00a0<\/strong><\/p><p><strong>L\u00f6sung:<\/strong><\/p><ul><li>Bereiten Sie ein Guckfenster aus einer Glasplatte vor, besser jedoch ein St\u00fcck Plexiglas\/Polycarbonat, mit dem Sie die gesamte Fl\u00e4che des Bienenstocks abdecken, vorzugsweise mit etwas \u00dcberstand.<\/li><li>Glas ist sch\u00f6n und besser zum Fotografieren, aber es ist schwer und man kann es zerbrechen oder sich verletzen, wenn man damit hantiert.<\/li><li>Kleben Sie die R\u00e4nder dieses Fensters mit Klebeband ab, damit Sie sich nicht verletzen.<\/li><li>Sie m\u00fcssen keine Latten am Dach\u00fcberstand anbringen.<\/li><\/ul><h4><strong>Wie man ein Guckloch verwendet<\/strong><\/h4><ul><li>Entfernen Sie vorsichtig das Dach \u2013 die Ersch\u00fctterungen st\u00f6ren die Bewohner und sie werden nachsehen, was passiert \ud83d\ude42<\/li><li>Entfernen Sie das Abdecktuch, schieben Sie dann vorsichtig und langsam das Beobachtungsfenster darunter. Achten Sie jedoch darauf, keine Hummel zu zerquetschen.<\/li><li>Jetzt k\u00f6nnen Sie das Geschehen im Nest beobachten.<\/li><li>Sobald Sie die Beobachtung beendet haben, decken Sie das Beobachtungsfenster mit einem Tuch ab und lassen Sie das Nest sich beruhigen.<\/li><li>Ziehen Sie dann vorsichtig das Sichtfenster heraus, richten Sie das feuchtigkeitsableitende Tuch so aus, dass keine Falten entstehen, und decken Sie das Tier mit dem Dach ab.<\/li><li>Wenn Sie schnell, entschlossen und ruhig arbeiten, k\u00f6nnen die Hummeln auf diese Art des Anbringens eines Beobachtungsfensters nicht reagieren.,<\/li><li>Wenn Sie allergisch auf Bienen-\/Hummelstiche reagieren, verwenden Sie Schutzkleidung (Schleier, Handschuhe, dickeres Hemd)<\/li><\/ul><div>Schauen Sie sich unsere an <strong>Fotonanleitung<\/strong>, der Ihnen alles erkl\u00e4ren wird.<\/div><div>\u00a0<\/div><p><strong>Empfehlung:\u00a0<\/strong><\/p><ul><li>Testen Sie das gesamte Verfahren an einem leeren Bienenstock, bevor Sie mit der Saison beginnen.<\/li><li>Sie werden selbst sehen, wie einfach das ist und die F\u00e4higkeit wird Ihnen n\u00fctzlich sein = Wer vorbereitet ist, wird nicht \u00fcberrascht<\/li><\/ul><div><h4 class=\"MsoNormal\"><strong>Regeln zur Beobachtung von Hummeln im Bienenstock<\/strong><\/h4><ul><li>St\u00f6ren Sie die K\u00f6nigin nicht, schon gar nicht, nachdem sie sich eingenistet hat.<\/li><li>Die Matte werden Sie an der Auskleidung nicht sehen, daher ist das Beobachten dessen von keinem praktischen Nutzen.<\/li><li>Abh\u00e4ngig von der Phase, in der sich das Nest befindet, sehen Sie darin Arbeiterinnen, junge K\u00f6niginnen oder auch M\u00e4nnchen (Drohnen).<\/li><li>Bitte verl\u00e4ngern Sie Ihre Beobachtung nicht unn\u00f6tig, da dies f\u00fcr Hummeln unnat\u00fcrlich ist.<br \/>Stockbienen betrachten Licht im Nest als Besch\u00e4digung der Nistmulde oder als Angriff auf das Nest.<\/li><li>Wenn M\u00e4nnchen (Drohnen) im Nest sind, aktiviert sie Licht und sie werden ihre Schwestern bel\u00e4stigen.<\/li><li>Beobachten Sie nicht zu oft, Sie st\u00f6ren die Hummelkolonie.<\/li><li>Denken Sie daran, dass die parasitische Wespe Melittobia acasta unbemerkt in den offenen Bienenstock eindringen kann. Der Bienenstock sollte daher nur f\u00fcr die unbedingt notwendige Zeit offen stehen gelassen werden.\u00a0<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cbf56b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbf56b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e7a165\" data-id=\"6e7a165\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-775f912 elementor-widget elementor-widget-text-editor\" data-id=\"775f912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3619\" style=\"width: 1519px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3619\" class=\"size-full wp-image-3619\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1.jpg\" alt=\"Hummeln PLUS - Beobachtungsfenster aus Polycarbonat\" width=\"1509\" height=\"1151\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1.jpg 1509w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-300x229.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-1024x781.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-768x586.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-1232x940.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-1416x1080.jpg 1416w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_1-1320x1007.jpg 1320w\" sizes=\"(max-width: 1509px) 100vw, 1509px\" \/><p id=\"caption-attachment-3619\" class=\"wp-caption-text\">\u00a01. Beobachtungsfenster aus Polycarbonat<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-557ad5e\" data-id=\"557ad5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b4ace4 elementor-widget elementor-widget-text-editor\" data-id=\"5b4ace4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3631\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3631\" class=\"wp-image-3631 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-300x169.jpg\" alt=\"Hummeln PLUS - Beobachtungsfenster Dach vorsichtig abnehmen\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3631\" class=\"wp-caption-text\">\u00a02. Vorsichtig den Deckel der Beute abnehmen<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48b688a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48b688a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d2024b0\" data-id=\"d2024b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2220302 elementor-widget elementor-widget-text-editor\" data-id=\"2220302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3620\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3620\" class=\"wp-image-3620 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-300x169.jpg\" alt=\"Hummeln PLUS - Beobachtungsfenster - Schieben Sie das Fenster unter die Abdeckplane\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_2-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3620\" class=\"wp-caption-text\">3. Schieben Sie das Fenster unter das Abdecktuch<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8b8c702\" data-id=\"8b8c702\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3c7dc9 elementor-widget elementor-widget-text-editor\" data-id=\"a3c7dc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3621\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-3621\" class=\"wp-image-3621 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-300x169.jpg\" alt=\"Hummel PLUS \u2013 Beobachtungsfenster aus Polycarbonat oben auf dem Bienenstock\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_3-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3621\" class=\"wp-caption-text\">4. Entfernen Sie das Tuch am Sichtfenster<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b741ff8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b741ff8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-029aaa7\" data-id=\"029aaa7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c41018 elementor-widget elementor-widget-text-editor\" data-id=\"9c41018\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3622\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3622\" class=\"wp-image-3622 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-300x169.jpg\" alt=\"Hummeln PLUS - Beobachtungsfenster - Hummelbeobachtung\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_4-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3622\" class=\"wp-caption-text\">5. Beobachtung von Hummeln durch ein Beobachtungsfenster<br \/>Foto O. Hercog<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1904175\" data-id=\"1904175\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3305c elementor-widget elementor-widget-text-editor\" data-id=\"7d3305c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3624\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3624\" class=\"wp-image-3624 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-300x169.jpg\" alt=\"Hummel PLUS - Beobachtungsfenster Tuch \u00fcber das Fenster legen\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_6-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3624\" class=\"wp-caption-text\">6. Bedecken Sie das Beobachtungsfenster nach dem Betrachten mit einem Tuch und ziehen Sie das Fenster langsam heraus<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4507f24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4507f24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a5b14fc\" data-id=\"a5b14fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f8f93 elementor-widget elementor-widget-text-editor\" data-id=\"79f8f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3631\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3631\" class=\"wp-image-3631 size-medium\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-300x169.jpg\" alt=\"Hummel PLUS - Beobachtungsfenster - Hauptabdeckung anpassen\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_8-1320x743.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3631\" class=\"wp-caption-text\">7. Gut abdecken<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b22c48a\" data-id=\"b22c48a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a687ed1 elementor-widget elementor-widget-text-editor\" data-id=\"a687ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3625\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3625\" class=\"wp-image-3625\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_7-e1580065615388.jpg\" alt=\"Hummel PLUS - Beobachtungsfenster - R\u00fcckseite des Daches aufsetzen\" width=\"300\" height=\"344\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_7-e1580065615388.jpg 540w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_7-e1580065615388-262x300.jpg 262w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3625\" class=\"wp-caption-text\">Setzen Sie die Beuteabdeckung wieder auf.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-64865bb elementor-widget elementor-widget-text-editor\" data-id=\"64865bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_3623\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3623\" class=\"wp-image-3623\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-300x169.jpg\" alt=\"Hummel PLUS - Beobachtungsfenster - Hummelbeobachtung\" width=\"450\" height=\"253\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-300x169.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-1024x576.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-768x432.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-1536x864.jpg 1536w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-1232x693.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-scaled.jpg 1920w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Pozorovaci_okenko_5-1320x743.jpg 1320w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-3623\" class=\"wp-caption-text\">Paarungsversuch von Geschwistern im Nest im Licht.\u00a0<br \/>Foto O. Hercog<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jak pozorovat \u010dmel\u00e1ky v \u00falku pozorovac\u00ed ok\u00e9nko a jeho pou\u017eit\u00ed O pozorovac\u00edm ok\u00e9nku v \u010dmel\u00e1\u010d\u00edm \u00falku (\u010dmel\u00ednu) V\u0161echny zaj\u00edm\u00e1, jak si \u017eij\u00ed \u010dmel\u00e1ci v \u00falku a cht\u011bj\u00ed se pod\u00edvat a pozorovat, jak \u017ee to v tom hn\u00edzd\u011b opravdu chod\u00ed. Pokud otev\u0159ete \u00falek, sv\u011btlo v\u00a0hn\u00edzd\u011b pova\u017euj\u00ed \u010dmel\u00e1ci\u00a0za po\u0161kozen\u00ed hn\u00edzdn\u00ed dutiny p\u0159\u00edpadn\u011b za \u00fatok na hn\u00edzdo =&nbsp;&hellip;<\/p>","protected":false},"author":4,"featured_media":3650,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"wf_page_folders":[23],"class_list":["post-3599","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pozorovac\u00ed ok\u00e9nko \u00falu &#8211; \u010cmel\u00e1ci PLUS<\/title>\n<meta name=\"description\" content=\"N\u00e1vod jak vytvo\u0159it pozorovac\u00ed ok\u00e9nko v \u010dmel\u00e1\u010d\u00edm \u00falu \u010cemu se vyvarovat, jak\u00fd zp\u016fsob zvolit aby bylo funk\u010dn\u00ed a bezpe\u010dn\u00e9 pro \u010dmel\u00e1ky i chovatele\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmelaciplus.cz\/de\/beobachtungsfenster-ulu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pozorovac\u00ed ok\u00e9nko \u00falu &#8211; \u010cmel\u00e1ci PLUS\" \/>\n<meta property=\"og:description\" content=\"N\u00e1vod jak vytvo\u0159it pozorovac\u00ed ok\u00e9nko v \u010dmel\u00e1\u010d\u00edm \u00falu \u010cemu se vyvarovat, jak\u00fd zp\u016fsob zvolit aby bylo funk\u010dn\u00ed a bezpe\u010dn\u00e9 pro \u010dmel\u00e1ky i chovatele\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmelaciplus.cz\/de\/beobachtungsfenster-ulu\/\" \/>\n<meta property=\"og:site_name\" content=\"\u010cmel\u00e1ci PLUS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cmelaciplus\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T16:28:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Popozorovaci_okenko.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"772\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cmelaci\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/\",\"name\":\"Pozorovac\u00ed ok\u00e9nko \u00falu &#8211; \u010cmel\u00e1ci PLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cmelaci_PLUS_Popozorovaci_okenko.jpg\",\"datePublished\":\"2020-01-26T15:56:54+00:00\",\"dateModified\":\"2024-03-08T16:28:13+00:00\",\"description\":\"N\u00e1vod jak vytvo\u0159it pozorovac\u00ed ok\u00e9nko v \u010dmel\u00e1\u010d\u00edm \u00falu \u010cemu se vyvarovat, jak\u00fd zp\u016fsob zvolit aby bylo funk\u010dn\u00ed a bezpe\u010dn\u00e9 pro \u010dmel\u00e1ky i chovatele\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cmelaci_PLUS_Popozorovaci_okenko.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Cmelaci_PLUS_Popozorovaci_okenko.jpg\",\"width\":772,\"height\":611,\"caption\":\"Pozorovac\u00ed ok\u00e9nko \u00falku (\u010dmel\u00ednu) Foto: O Hercog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/pozorovaci-okenko-ulu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pozorovac\u00ed ok\u00e9nko \u00falu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#website\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\",\"name\":\"\u010cmel\u00e1ci PLUS\",\"description\":\"\u010cmel\u00e1ci PLUS Pom\u00e1h\u00e1me \u010dmel\u00e1k\u016fm a p\u0159\u00edrod\u011b -  Unik\u00e1tn\u00ed encyklopedie \u010dmel\u00e1k\u016f\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#organization\",\"name\":\"\u010cmel\u00e1ci PLUS z.s.\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png\",\"contentUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png\",\"width\":50,\"height\":50,\"caption\":\"\u010cmel\u00e1ci PLUS z.s.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cmelaciplus\",\"https:\\\/\\\/x.com\\\/cmelaci\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHMo-5xkRu3J-vM9UVzOl9Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beobachtungsfenster f\u00fcr den Bienenstock \u2013 Hummeln PLUS","description":"Anleitung zur Erstellung eines Beobachtungsfensters in einem Hummelnest Welches Vorgehen zu vermeiden ist, welche Methode zu w\u00e4hlen ist, um es f\u00fcr Hummeln und Z\u00fcchter funktionsf\u00e4hig und sicher zu machen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmelaciplus.cz\/de\/beobachtungsfenster-ulu\/","og_locale":"de_DE","og_type":"article","og_title":"Pozorovac\u00ed ok\u00e9nko \u00falu &#8211; \u010cmel\u00e1ci PLUS","og_description":"N\u00e1vod jak vytvo\u0159it pozorovac\u00ed ok\u00e9nko v \u010dmel\u00e1\u010d\u00edm \u00falu \u010cemu se vyvarovat, jak\u00fd zp\u016fsob zvolit aby bylo funk\u010dn\u00ed a bezpe\u010dn\u00e9 pro \u010dmel\u00e1ky i chovatele","og_url":"https:\/\/www.cmelaciplus.cz\/de\/beobachtungsfenster-ulu\/","og_site_name":"\u010cmel\u00e1ci PLUS","article_publisher":"https:\/\/www.facebook.com\/cmelaciplus","article_modified_time":"2024-03-08T16:28:13+00:00","og_image":[{"width":772,"height":611,"url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Popozorovaci_okenko.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cmelaci","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/","url":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/","name":"Beobachtungsfenster f\u00fcr den Bienenstock \u2013 Hummeln PLUS","isPartOf":{"@id":"https:\/\/www.cmelaciplus.cz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/#primaryimage"},"image":{"@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Popozorovaci_okenko.jpg","datePublished":"2020-01-26T15:56:54+00:00","dateModified":"2024-03-08T16:28:13+00:00","description":"Anleitung zur Erstellung eines Beobachtungsfensters in einem Hummelnest Welches Vorgehen zu vermeiden ist, welche Methode zu w\u00e4hlen ist, um es f\u00fcr Hummeln und Z\u00fcchter funktionsf\u00e4hig und sicher zu machen","breadcrumb":{"@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/#primaryimage","url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Popozorovaci_okenko.jpg","contentUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/01\/Cmelaci_PLUS_Popozorovaci_okenko.jpg","width":772,"height":611,"caption":"Pozorovac\u00ed ok\u00e9nko \u00falku (\u010dmel\u00ednu) Foto: O Hercog"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmelaciplus.cz\/pozorovaci-okenko-ulu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.cmelaciplus.cz\/"},{"@type":"ListItem","position":2,"name":"Pozorovac\u00ed ok\u00e9nko \u00falu"}]},{"@type":"WebSite","@id":"https:\/\/www.cmelaciplus.cz\/#website","url":"https:\/\/www.cmelaciplus.cz\/","name":"Hummeln PLUS","description":"Hummel PLUS Wir helfen Hummeln und der Natur \u2013 Einzigartige Hummel-Enzyklop\u00e4die","publisher":{"@id":"https:\/\/www.cmelaciplus.cz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmelaciplus.cz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cmelaciplus.cz\/#organization","name":"Hummeln PLUS e.V.","url":"https:\/\/www.cmelaciplus.cz\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cmelaciplus.cz\/#\/schema\/logo\/image\/","url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png","contentUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png","width":50,"height":50,"caption":"\u010cmel\u00e1ci PLUS z.s."},"image":{"@id":"https:\/\/www.cmelaciplus.cz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cmelaciplus","https:\/\/x.com\/cmelaci","https:\/\/www.youtube.com\/channel\/UCHMo-5xkRu3J-vM9UVzOl9Q"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/3599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/comments?post=3599"}],"version-history":[{"count":35,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/3599\/revisions"}],"predecessor-version":[{"id":33399,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/3599\/revisions\/33399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/media\/3650"}],"wp:attachment":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/media?parent=3599"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/wf_page_folders?post=3599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}