{"id":4651,"date":"2020-02-15T21:58:49","date_gmt":"2020-02-15T21:58:49","guid":{"rendered":"https:\/\/www.cmelaciplus.cz\/?page_id=4651"},"modified":"2026-05-10T00:00:55","modified_gmt":"2026-05-09T22:00:55","slug":"mutter-sucht-brutstatte","status":"publish","type":"page","link":"https:\/\/www.cmelaciplus.cz\/de\/matka-hleda-hnizdiste\/","title":{"rendered":"Mutter sucht Brutplatz"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4651\" class=\"elementor elementor-4651\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3591f77d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3591f77d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-579db27d\" data-id=\"579db27d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68050884 elementor-widget elementor-widget-heading\" data-id=\"68050884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie unterscheidet man eine etablierte Hummel von einer suchenden K\u00f6nigin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f4fb086 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f4fb086\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5380c7f5\" data-id=\"5380c7f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ed7924 elementor-widget elementor-widget-spacer\" data-id=\"78ed7924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b9052bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b9052bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51f6ce9\" data-id=\"51f6ce9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07ec64e elementor-nav-menu--dropdown-mobile elementor-nav-menu__align-start elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-global elementor-global-33299 elementor-widget-nav-menu\" data-id=\"07ec64e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-chevron-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-07ec64e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-799\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/rad-bych-zacal-chovat-cmelaky\/\" class=\"elementor-item\">Ich m\u00f6chte mit der Haltung von Hummeln beginnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-prvni-uvaha\/\" class=\"elementor-item\">Die notwendige erste \u00dcberlegung<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3766\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-ziskat-cmelaky\/\" class=\"elementor-item\">Wie man Hummeln bekommt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-802\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vybrat-spravny-ul\/\" class=\"elementor-item\">Wie w\u00e4hlt man den richtigen Turm aus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38041\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-vybava-ulu\/\" class=\"elementor-item\">Notwendige Bienenstockausstattung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-805\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/chodba-v-ulu\/\" class=\"elementor-sub-item\">Gang in der Bienenstock<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-806\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vetrani\/\" class=\"elementor-sub-item\">Bienenstockentl\u00fcftung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka\/\" class=\"elementor-sub-item\">Klapka<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-5373\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka-zvedani-zaklopky\/\" class=\"elementor-sub-item\">L\u00f6sung zum Anheben des Klappenschlosses<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2892\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/strecha-cmelaciho-ulu\/\" class=\"elementor-sub-item\">Dach des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25831\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/tepelna-izolace-a-vytapeni-ulku-pro-cmelaky\/\" class=\"elementor-sub-item\">W\u00e4rmed\u00e4mmung und Heizung von Beuten<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3606\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-vytah-k-bezpecne-kontrole-hnizd\/\" class=\"elementor-sub-item\">Hummelaufzug f\u00fcr sichere Eingriffe ins Nest<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vystelka\/\" class=\"elementor-sub-item\">Auskleidung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3607\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pozorovaci-okenko-ulu\/\" class=\"elementor-sub-item\">Guckloch des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38137\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">======================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-chovatele-cmelaku\/\" class=\"elementor-item\">Z\u00fcchterhilfen<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37248\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-odchyt-a-usazeni-kralovny\/\" class=\"elementor-sub-item\">Hilfsmittel zum Fangen und Einsetzen der K\u00f6nigin<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37247\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-bezpecnou-kontrolu-v-ulku\/\" class=\"elementor-sub-item\">Hilfsmittel f\u00fcr die sichere Kontrolle des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38138\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">=================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37249\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/krmeni-krmitka-prikrmovani-cmelaku\/\" class=\"elementor-item\">F\u00fctterung und Zuf\u00fctterung von Hummeln<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-893\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kudy-cesta-nevede\/\" class=\"elementor-item\">GEF\u00c4HRLICHE Dinge f\u00fcr Hummeln<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8405\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodne-komercne-dostupne-ulky\/\" class=\"elementor-sub-item\">Ungeeignete im Handel erh\u00e4ltliche Rohlinge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30192\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nebezpecne-pripravky-proti-parazitum\/\" class=\"elementor-sub-item\">Gef\u00e4hrliche Parasitenbek\u00e4mpfungsmittel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5884\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prodej-nepuvodnich-druhu-cmelaku\/\" class=\"elementor-sub-item\">Verkauf von nicht-einheimischen Hybriden von Nutzpflanzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5843\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodna-odchytova-sada\/\" class=\"elementor-sub-item\">Ungeeignetes Fangset<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30193\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\">Bacillus thuringiensis: Risiko oder Nutzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38139\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">============================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38090\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pripravna-faze-chovu-cmelaku-v-ulku\/\" class=\"elementor-item\">Vorbereitungsphase der Zucht<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33503\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/priprava-ulku-pred-sezonou\/\" class=\"elementor-sub-item\">Vorbereitung des Magens vor der Saison<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26457\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2854\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\">Ameisen und der Schutz des Bienenstocks vor ihnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26750\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\">Wundermittel zum Schutz?<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nejcastejsi-chyby\/\" class=\"elementor-sub-item\">Die h\u00e4ufigsten Fehler<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-813\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu\/\" class=\"elementor-sub-item\">Auswahl Ihrer Anfragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38134\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===========================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38109\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-sezona-zacina\/\" class=\"elementor-item\">Die Hummel-Saison beginnt<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author nmr-logged-in menu-item menu-item-type-post_type menu-item-object-page menu-item-2463\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prvni-krok-nez-zahajite-sezonu\/\" class=\"elementor-sub-item\">Erste Schritte, bevor Sie die Saison beginnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26458\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33532\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umisteni-ulu-na-zahrade\/\" class=\"elementor-sub-item\">Wo platziere ich die Beute richtig<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4692\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-hleda-hnizdiste\/\" class=\"elementor-sub-item\">Mutter sucht Brutplatz<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-815\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-usadit-kralovnu-do-ulku\/\" class=\"elementor-sub-item\">Wie man eine Hummel in einen Bienenstock setzt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36889\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/atraktant-pro-obsazeni-ulku-s-cmelaky\/\" class=\"elementor-sub-item\">Lockstoff f\u00fcr Hummelnestbesiedlung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-797\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/mam-nebo-nemam-usazeno\/\" class=\"elementor-sub-item\">Habe ich oder habe ich nicht sesshaft geworden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5983\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-se-usadila-v-hnizdisti\/\" class=\"elementor-sub-item\">Die Mutter lie\u00df sich im Nest nieder<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-796\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umeni-klapky\/\" class=\"elementor-sub-item\">Die Kunst des Klappens<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-795\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/extremni-vlivy-jara-mraziky\/\" class=\"elementor-sub-item\">Extremwetter im Fr\u00fchling: Frost<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6940\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-a-jak-vetrat-ulek\/\" class=\"elementor-sub-item\">Wann und wie man eine Bienenstockkiste mit Hummeln l\u00fcftet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38136\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===============================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33573\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-hnizdo-v-dobe-delnic\/\" class=\"elementor-item\">Einzelne Phase der Mutter und der ersten Arbeiterinnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7049\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kontroly-hnizda-v-ulku\/\" class=\"elementor-item\">Pflege eines ausgebauten Wabenfunds im Bienenstock<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38115\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/parazite-a-predatori-ve-cmelacim-ulu\/\" class=\"elementor-item\">Parasiten und Raubtiere im Bienenstock<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pacmelaci-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Hummeln und Hummelzucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6786\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zavijec-cizopasny-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Zav\u00edje\u010d cizopasn\u00fd Aphomia sociella und Zucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18210\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/melittobia-acasta-a-chov-cmelaku\/\" class=\"elementor-sub-item\">Melittobia acasta ein chov<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6709\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\">Ameisen und deren Bek\u00e4mpfung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38140\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">===================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32968\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">Ende der Hummelkolonie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prohlidka-ulu-a-hnizda-na-konci-sezony\/\" class=\"elementor-sub-item\">Inspektion des Bienenstocks und des Nestes am Ende der Saison<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-850\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vycistit-a-zazimovat-ul\/\" class=\"elementor-sub-item\">Wie man einen Bienenstock reinigt und \u00fcberwintert<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\">================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-793\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu-2\/\" class=\"elementor-item\">Auswahl Ihrer Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-894\"><a href=\"http:\/\/www.cmelaciplus.cz\/de\/\" class=\"elementor-item\">Zur\u00fcck zum Anfang<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-07ec64e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-799\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/rad-bych-zacal-chovat-cmelaky\/\" class=\"elementor-item\" tabindex=\"-1\">Ich m\u00f6chte mit der Haltung von Hummeln beginnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-800\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-prvni-uvaha\/\" class=\"elementor-item\" tabindex=\"-1\">Die notwendige erste \u00dcberlegung<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3766\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-ziskat-cmelaky\/\" class=\"elementor-item\" tabindex=\"-1\">Wie man Hummeln bekommt<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-802\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vybrat-spravny-ul\/\" class=\"elementor-item\" tabindex=\"-1\">Wie w\u00e4hlt man den richtigen Turm aus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38041\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nezbytna-vybava-ulu\/\" class=\"elementor-item\" tabindex=\"-1\">Notwendige Bienenstockausstattung<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-805\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/chodba-v-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gang in der Bienenstock<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-806\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vetrani\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bienenstockentl\u00fcftung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-808\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Klapka<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-5373\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/klapka-zvedani-zaklopky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">L\u00f6sung zum Anheben des Klappenschlosses<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2892\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/strecha-cmelaciho-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Dach des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-25831\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/tepelna-izolace-a-vytapeni-ulku-pro-cmelaky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">W\u00e4rmed\u00e4mmung und Heizung von Beuten<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3606\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-vytah-k-bezpecne-kontrole-hnizd\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hummelaufzug f\u00fcr sichere Eingriffe ins Nest<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-809\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vystelka\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Auskleidung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-3607\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pozorovaci-okenko-ulu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Guckloch des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38137\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">======================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-chovatele-cmelaku\/\" class=\"elementor-item\" tabindex=\"-1\">Z\u00fcchterhilfen<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37248\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-odchyt-a-usazeni-kralovny\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hilfsmittel zum Fangen und Einsetzen der K\u00f6nigin<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37247\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pomucky-pro-bezpecnou-kontrolu-v-ulku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hilfsmittel f\u00fcr die sichere Kontrolle des Bienenstocks<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38138\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">=================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-37249\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/krmeni-krmitka-prikrmovani-cmelaku\/\" class=\"elementor-item\" tabindex=\"-1\">F\u00fctterung und Zuf\u00fctterung von Hummeln<\/a><\/li>\n<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-893\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kudy-cesta-nevede\/\" class=\"elementor-item\" tabindex=\"-1\">GEF\u00c4HRLICHE Dinge f\u00fcr Hummeln<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8405\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodne-komercne-dostupne-ulky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ungeeignete im Handel erh\u00e4ltliche Rohlinge<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30192\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nebezpecne-pripravky-proti-parazitum\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gef\u00e4hrliche Parasitenbek\u00e4mpfungsmittel<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5884\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prodej-nepuvodnich-druhu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Verkauf von nicht-einheimischen Hybriden von Nutzpflanzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5843\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nevhodna-odchytova-sada\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ungeeignetes Fangset<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-30193\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Bacillus thuringiensis: Risiko oder Nutzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38139\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">============================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38090\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pripravna-faze-chovu-cmelaku-v-ulku\/\" class=\"elementor-item\" tabindex=\"-1\">Vorbereitungsphase der Zucht<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33503\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/priprava-ulku-pred-sezonou\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vorbereitung des Magens vor der Saison<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26457\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-2854\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ameisen und der Schutz des Bienenstocks vor ihnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26750\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zazracny-pripravek-na-ochranu-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wundermittel zum Schutz?<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-811\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/nejcastejsi-chyby\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die h\u00e4ufigsten Fehler<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-813\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Auswahl Ihrer Anfragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38134\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===========================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38109\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-sezona-zacina\/\" class=\"elementor-item\" tabindex=\"-1\">Die Hummel-Saison beginnt<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"nmr-administrator nmr-editor nmr-author nmr-logged-in menu-item menu-item-type-post_type menu-item-object-page menu-item-2463\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prvni-krok-nez-zahajite-sezonu\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Erste Schritte, bevor Sie die Saison beginnen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-26458\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-umistit-ulky-pro-cmelaky-na-stanoviste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann die V\u00f6lker an ihren Standort stellen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33532\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umisteni-ulu-na-zahrade\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wo platziere ich die Beute richtig<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4692\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-hleda-hnizdiste\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Mutter sucht Brutplatz<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-815\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-usadit-kralovnu-do-ulku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wie man eine Hummel in einen Bienenstock setzt<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-36889\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/atraktant-pro-obsazeni-ulku-s-cmelaky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Lockstoff f\u00fcr Hummelnestbesiedlung<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-797\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/mam-nebo-nemam-usazeno\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Habe ich oder habe ich nicht sesshaft geworden<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5983\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/matka-se-usadila-v-hnizdisti\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die Mutter lie\u00df sich im Nest nieder<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-796\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/umeni-klapky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Die Kunst des Klappens<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-795\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/extremni-vlivy-jara-mraziky\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Extremwetter im Fr\u00fchling: Frost<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6940\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kdy-a-jak-vetrat-ulek\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wann und wie man eine Bienenstockkiste mit Hummeln l\u00fcftet<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38136\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===============================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-33573\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaci-hnizdo-v-dobe-delnic\/\" class=\"elementor-item\" tabindex=\"-1\">Einzelne Phase der Mutter und der ersten Arbeiterinnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7049\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/kontroly-hnizda-v-ulku\/\" class=\"elementor-item\" tabindex=\"-1\">Pflege eines ausgebauten Wabenfunds im Bienenstock<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38115\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/parazite-a-predatori-ve-cmelacim-ulu\/\" class=\"elementor-item\" tabindex=\"-1\">Parasiten und Raubtiere im Bienenstock<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6161\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/pacmelaci-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hummeln und Hummelzucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6786\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/zavijec-cizopasny-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Zav\u00edje\u010d cizopasn\u00fd Aphomia sociella und Zucht<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-18210\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/melittobia-acasta-a-chov-cmelaku\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Melittobia acasta ein chov<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6709\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/ochrana-cmelaciho-ulu-pred-mravenci\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Ameisen und deren Bek\u00e4mpfung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38140\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">===================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-32968\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Ende der Hummelkolonie<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7428\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/prohlidka-ulu-a-hnizda-na-konci-sezony\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Inspektion des Bienenstocks und des Nestes am Ende der Saison<\/a><\/li>\n\t<li class=\"nmr-administrator nmr-editor nmr-author menu-item menu-item-type-post_type menu-item-object-page menu-item-850\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/jak-vycistit-a-zazimovat-ul\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Wie man einen Bienenstock reinigt und \u00fcberwintert<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-38141\"><a href=\"#\" class=\"elementor-sub-item elementor-item-anchor\" tabindex=\"-1\">================================<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-793\"><a href=\"https:\/\/www.cmelaciplus.cz\/de\/vyber-z-vasich-dotazu-2\/\" class=\"elementor-item\" tabindex=\"-1\">Auswahl Ihrer Fragen<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-894\"><a href=\"http:\/\/www.cmelaciplus.cz\/de\/\" class=\"elementor-item\" tabindex=\"-1\">Zur\u00fcck zum Anfang<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-188681cb\" data-id=\"188681cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b276aad elementor-widget elementor-widget-text-editor\" data-id=\"b276aad\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"#\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong><em>Was Sie hier lernen werden<\/em><\/strong><\/h4><ul><li><em>Was macht eine Hummelk\u00f6nigin nach dem Aufwachen<\/em><\/li><li><em>Wie es einen Nistplatz sucht \u2013 Nistplatz<\/em><\/li><li><em>Wie erkennt man so eine Mutter zuverl\u00e4ssig?<\/em><\/li><li><em>Warum nisten sich M\u00fctter manchmal nicht ein, obwohl sie nach einem Nistplatz suchen<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4834e elementor-widget elementor-widget-text-editor\" data-id=\"7e4834e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"#\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i>Datum letzter Aktualisierung: 23.02.2024<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aff4798 elementor-widget elementor-widget-text-editor\" data-id=\"aff4798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><img decoding=\"async\" class=\"size-full wp-image-37899 alignleft\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2026\/05\/Cmelaci-PLUS-abstrakt-www-small.jpg\" alt=\"Seiten\u00fcbersicht\" width=\"150\" height=\"150\"><\/h4><ul>\n<li><strong>K\u00f6niginnen der Hummeln erwachen:<\/strong> Matky se probouzej\u00ed postupn\u011b, nejprve ran\u00e9 druhy \u2013 probud\u00ed je jarn\u00ed slun\u00ed\u010dko, kter\u00e9 otepl\u00ed zem, kde hibernuj\u00ed<\/li>\n<li><strong>Nach dem Aufwachen haben wir Hunger und Zeit zum Erkunden:<\/strong> Ihr erstes Ziel ist es, gen\u00fcgend Nahrung zu finden und nach dem langen Winterschlaf Energie zu tanken und sich aufzuw\u00e4rmen \u2013 deshalb fressen und ruhen sie oft<\/li>\n<li><strong>M\u00fctter tanzen im Fr\u00fchling:<\/strong> Sobald sie ihre Energie wieder aufgetankt haben, beginnen sie, nach Nistpl\u00e4tzen zu suchen \u2013 sie wollen nicht sofort nisten, aber sie sehen sich um und warten auf den richtigen Zeitpunkt, an dem es genug Nahrung gibt. Sie suchen am h\u00e4ufigsten am Boden und \u201etanzen\u201c ihren Suchflug<\/li>\n<li><strong>Typische Nistpl\u00e4tze von Hummeln nach Hummelart:<\/strong> Nester von Kleinnagern im Boden, Vogelnestk\u00e4sten und verlassene Nester, Stapel alten Grases und Rasen, D\u00e4mmungen in D\u00e4chern und Dachb\u00f6den, alte Decken und Teppiche, eine Decke in der Hundeh\u00fctte usw.<\/li>\n<li><strong>In das Nest darf kein Wasser eindringen:<\/strong> Hummeln suchen instinktiv nach Orten, an denen sie nicht vom Regen weggesp\u00fclt werden.<\/li>\n<li><strong>Stare und K\u00f6niginnen kehren nach Hause zur\u00fcck:<\/strong> Wenn die M\u00fctter die Hibernation \u00fcberleben, treibt sie der Instinkt zu dem Ort, an dem die Geburtsst\u00e4tte war. Das ist f\u00fcr die Z\u00fcchter sowohl eine Freude als auch eine Sorge.<\/li>\n<li><strong>Respektieren Sie die K\u00f6niginnen im Fr\u00fchling:<\/strong> Wenn Sie eine Hummelmama beim Ausruhen finden, respektieren Sie sie. Wenn sie nachweislich in Not ist, k\u00f6nnen Sie ihr helfen, aber \u00fcberlegen Sie, ob sie diese wirklich braucht.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e374595 elementor-widget elementor-widget-text-editor\" data-id=\"e374595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Inhalt<\/strong><\/h4><p><strong><a href=\"#1\">Einleitung<\/a><\/strong><br \/><strong><a href=\"#2\">Die K\u00f6niginnen erwachen<\/a><\/strong><br \/><strong><a href=\"#3\">Welche Nistpl\u00e4tze suchen Hummeln?<\/a><\/strong><br \/><strong><a href=\"#4\">Wie erkennt man eine Mutter, die einen Nistplatz sucht?<\/a><\/strong><br \/><strong><a href=\"#5\">Wenn eine Mutter nach einem Nistplatz sucht, br\u00fctet sie dort dann immer?<\/a><\/strong><br \/><strong><a href=\"#6\">Wie unterscheidet man eine Mutter, die ein Nest sucht, von einer, die keins sucht?<\/a><\/strong><br \/><strong><a href=\"#7\">Was passiert, wenn sich mehrere M\u00fctter an einem geeigneten Nistplatz treffen?<\/a><br \/><a href=\"#8\">Brauchen M\u00fctter im Fr\u00fchling Hilfe \u2013 wann ja und wenn ja, welche?<\/a><\/strong><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbad06b elementor-widget elementor-widget-text-editor\" data-id=\"bbad06b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"1\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Einleitung<\/strong><\/h4>\n<p class=\"MsoNormal\">In diesem Kapitel werden wir uns mit einem wichtigen Detail aus dem Leben der K\u00f6niginmutter befassen, und zwar mit <strong>die Suche nach einem geeigneten Nistplatz<\/strong>, also <b>Brutst\u00e4tte<\/b>. Wir kn\u00fcpfen an das Kapitel an&nbsp;<a href=\"https:\/\/www.cmelaciplus.cz\/de\/wie-es-im-hummelnest-zugeht\/\" target=\"_blank\" rel=\"noopener\">Aus dem Leben der Hummeln \u2013 wie es im Nest zugeht<\/a>.<\/p>\n<p>Wenn die Hummelk\u00f6nigin aufwacht, wartet viel Arbeit auf sie und deshalb sucht sie bald nach einem Nistplatz. Zuerst muss sie sich jedoch <strong>st\u00e4rken<\/strong> und \u00fcberpr\u00fcfen, ob es in der N\u00e4he ist <strong>genug zu essen<\/strong>.<\/p>\n<p>Es ist interessant zu sehen, wie die Mutter nach einem Nistplatz sucht. Eine solche Situation k\u00f6nnen wir <strong>im Fr\u00fchling sehen<\/strong>, wenn sie nach dem Winterschlaf Nester suchen. <br>Mit etwas Gl\u00fcck l\u00e4sst sich eine \u00e4hnliche Situation beobachten <strong>und zu Beginn des Sommers<\/strong>, wenn tr\u00e4chtige Weibchen versuchen, sich einzunisten, die sich entschieden haben, nicht zu \u00fcberwintern. Solche F\u00e4lle sind jedoch seltener als im Fr\u00fchling.<\/p>\n<p>Es ist wichtig, die M\u00fctter und ihren Flug sowie ihr Verhalten zu beobachten. Daran erkennen wir, <b>dass die Brutst\u00e4tte wirklich gesucht wird<\/b>. Dies ist von enormer Bedeutung, damit <strong>Der Z\u00fcchter hat richtig entschieden<\/strong> ob, ob, ob.<\/p>\n<p>Man muss sich aber bewusst sein, dass <strong>obwohl die Mutter nach einem Nistplatz sucht, will sie sich nicht immer sofort niederlassen<\/strong>.Manchmal tut es wirklich nur <strong>schaut sich um<\/strong> a <strong>w\u00e4hlt<\/strong> Hier ist der Ort, <strong>Er kommt sp\u00e4ter zur\u00fcck<\/strong> . Bis sie selbst bereit ist und wenn es wirklich<strong> geeignete Bedingungen<\/strong>.<\/p>\n<p>Ungeduld und Hartn\u00e4ckigkeit ist <b>&nbsp;ein h\u00e4ufiger Fehler von Anf\u00e4ngern, der zum Scheitern f\u00fchrt<\/b>. Der Versuch, eine Hummelk\u00f6nigin sofort einzusetzen, oder&nbsp;<strong>Zu erwarten, dass er sich nach einem festen Algorithmus und Ihrem Plan verh\u00e4lt, ist ebenfalls ein Fehler<\/strong>.&nbsp;<\/p>\n<p>brauchen die Dinge Zeit und <strong>nicht auf die Tube dr\u00fccken<\/strong>. Mit der Zeit lernt der Z\u00fcchter <b>die Natur respektieren<\/b> und dass er sich nicht so verh\u00e4lt, wie er es sich w\u00fcnschen w\u00fcrde. Ein erfahrener Z\u00fcchter erkennt dann anhand einer Reihe von Merkmalen, dass er auf eine br\u00fctwillige Mutter getroffen ist. Aber das erfordert jahrelange \u00dcbung...<\/p>\n<p>Wir werden diesem Thema ausreichend Raum widmen.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-592c4cd elementor-widget elementor-widget-text-editor\" data-id=\"592c4cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4705\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-4705\" class=\"wp-image-4705\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg\" alt=\"Hummeln PLUS - Hummelk\u00f6nigin (Bombus terrestris) sucht Brutst\u00e4tte\" width=\"450\" height=\"450\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker-300x300.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker-150x150.jpg 150w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker-768x768.jpg 768w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-4705\" class=\"wp-caption-text\">Hummelmutter nach dem Erwachen<br \/>Foto Flimmer<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24009d6 elementor-widget elementor-widget-text-editor\" data-id=\"24009d6\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"2\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Die K\u00f6niginnen erwachen<\/strong><\/h4><p>Hummelm\u00fctter<strong> erscheinen nach und nach<\/strong> \u2013 <strong>nach Art<\/strong> und vor allem nach dem Wetter, vor allem<strong> nach Lufttemperatur<\/strong> a <strong>B\u00f6den<\/strong>, in denen sie schliefen.<\/p><p>Sie erscheinen allm\u00e4hlich, wenn die H\u00f6he ansteigt oder in tiefen, kalten T\u00e4lern. Der Unterschied kann sogar Wochen betragen. Das Gesamtklima und die Situation beeinflussen ebenfalls alles.<\/p><p><strong><em>Beispiel<\/em><\/strong><\/p><p><em>Anfang M\u00e4rz 2020 hatten bereits viele Imker ihre Mutterst\u00e4mme bestiftet. Danach kamen zwei K\u00e4ltewellen<\/em><\/p><p><em>In der ersten M\u00e4rzwoche 2021 beobachteten wir eine Reihe von fr\u00fchzeitig erwachten Weibchen, aber keines unternahm noch Erkundungsfl\u00fcge \u2013 es versuchte nicht, einen Nistplatz zu finden<\/em><\/p><p><strong>Als erstes<\/strong> k\u00f6nnen sich K\u00f6niginnen von Gartenhummeln (Bombus lucorum) und Ackerhummeln (Bombus terrestris) zeigen. Diese k\u00f6nnen sich bei sch\u00f6nem Wetter bereits<strong> Anfang M\u00e4rz \u2013 April<\/strong>. <br \/>Diese Arten rechnen mit <strong>Risiko<\/strong>, dass sie nicht genug Nahrung finden werden. Wenn sie welche finden, gibt es relativ wenig Nahrungskonkurrenz, sie sehen dies als Vorteil an und gehen deshalb <strong>eines solchen Risikos<\/strong>.<\/p><p>Die K\u00f6niginnen der Waldhummel (Bombus sylvarum) erscheinen bald<strong> als Letzte bis Mai oder Juni<\/strong>.<\/p><p>Mit dem sich ver\u00e4ndernden Klima verschiebt sich jedoch auch die Erweckungszeit der Muttertiere. Die steigende Bodentemperatur, in der sie Winterschlaf gehalten haben, und die Sonneneinstrahlung, die nicht durch Wolken oder Schneedecke ged\u00e4mpft wird, wecken die Muttertiere. Die Grenze zwischen Winter und Fr\u00fchling wird immer unsch\u00e4rfer... Doch das sich ver\u00e4ndernde Klima bringt auch <strong>markant<\/strong> <strong>Wetterkapriolen<\/strong>, ist unser Beispiel.<\/p><p>Wenn sich die Mutterk\u00f6nigin vom Winterschlaf erholt, muss sie zuerst <strong>st\u00e4rken und erholen<\/strong>. Deshalb interessiert es sich zuerst f\u00fcr <strong>F\u00fctterung<\/strong>. <br \/><strong>Ich wiege ein Brot<\/strong>, die sie verloren hat \u2013 deshalb interessiert sie sich f\u00fcr den Nektar der Fr\u00fchlingsblumen, der eine Energiequelle darstellt, und f\u00fcr den Pollen, der f\u00fcr sie eine Proteinquelle ist. W\u00e4hrend der gesamten Winterstarre hat sie Energie aus ihrem Fettk\u00f6rper bezogen.<br \/>Die Mutter wei\u00df gut, dass sie sich danach bis zum Ende ihres Lebens nicht mehr ausruhen wird, und wenn sie nicht stark ist, wird sie ihre Aufgabe, \u201edie n\u00e4chste Generation zu gr\u00fcnden\u201e, nicht erf\u00fcllen k\u00f6nnen.\u00a0<strong>Die Mutter ern\u00e4hrt sich also von den Bl\u00fcten<\/strong>.<\/p><p>Wenn sie entdecken, <strong>dass g\u00fcnstige Bedingungen entstanden sind<\/strong>, beginnt sie allm\u00e4hlich, nach einem Ort zu suchen, an dem sie ein Nest bauen k\u00f6nnte. Mit der Aufnahme frischer Nahrung werden auch Prozesse aktiviert, die zu <strong>Eierstockentwicklung<\/strong>.<\/p><p><strong>Erst dann ist die Mutter bereit, ein Nest zu bauen und beginnt aktiv damit, danach zu suchen<\/strong>.<\/p><p><em><strong>Interessant<\/strong><\/em><\/p><ul><li><em>Als Letzte erwacht <strong>Mutter von Hummeln<\/strong>. Sie werden auch herumschn\u00fcffeln, aber sie suchen nicht nach einem Nistplatz, sondern nach einem Hummelnest, das sie \u00fcbernehmen k\u00f6nnen. Deshalb erwachen die Hummelk\u00f6niginnen als letzte \u2013 sie warten auf den richtigen Moment, oft tiefer vergraben als die Hummelk\u00f6niginnen, die sie parasitieren wollen.<\/em><br \/><em>Mehr \u00fcber Pa\u010dmel\u00e1ks erfahren Sie <a href=\"https:\/\/www.cmelaciplus.cz\/de\/pacmelaci-a-chov-cmelaku\/\" target=\"_blank\" rel=\"noopener\">auf der Seite Hummeln und die Zucht von Hummeln<\/a><\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ae7bf elementor-widget elementor-widget-video\" data-id=\"b2ae7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/rv_WQ_EPWxQ&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8ac8e elementor-widget elementor-widget-text-editor\" data-id=\"9c8ac8e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"3\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Welche Nistpl\u00e4tze suchen Hummeln?<\/strong><\/h4><p>K\u00f6niginnen der Hummelk\u00f6niginnen <strong>suchen prim\u00e4r nach Hohlr\u00e4umen<\/strong>und wo sie sich niederlassen und ihr Nest bauen. Eine Ausnahme bilden beispielsweise die Ackerhummeln (Bombus pascuorum), die sich auch in einem Haufen alten Grases niederlassen.<\/p><p>Hummeln k\u00f6nnen keine Hohlr\u00e4ume schaffen oder Nester aus Papiermasse bauen, wie es beispielsweise Bienen und Hornissen tun. <b>Gr\u00f6\u00dfe der Kavit\u00e4t<\/b> die sie sucht, entspricht den Bed\u00fcrfnissen ihrer Art. Die Anzahl der Individuen in einem Nest schwankt je nach Art und Bedingungen zwischen 50 und 800.<\/p><p><strong>Im Land\u00a0<\/strong><br \/>Manche Hummelarten suchen <strong>Pflichten im Land<\/strong>, zum Beispiel <a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaciplus-katalog-druhu-cmelaku-cmelak-zemni-bombus-terrestris\/\" target=\"_blank\" rel=\"noopener\">Dunkle Erdhummel (Bombus terrestris)<\/a>, <a href=\"https:\/\/www.cmelaciplus.cz\/de\/hummelartenkatalog-hummel-hummel-hajovy-bombus-lucorum\/\" target=\"_blank\" rel=\"noopener\">Helle Erdhummel (Bombus lucorum)<\/a> Himmel <strong>H\u00f6hlen in W\u00e4nden und Felsen<\/strong> zum Beispiel <a href=\"https:\/\/www.cmelaciplus.cz\/de\/cmelaciplus-katalog-der-hummelarten-hummelstein-hummel-bombus-lapidarius\/\" target=\"_blank\" rel=\"noopener\">Steinhummel ( Bombus lapidarius )<\/a>.\u00a0<\/p><p><strong>2. Ruinen in B\u00e4umen mit Vogelnestern, Vogelh\u00e4usern, Dachd\u00e4mmung\u00a0<\/strong><\/p><p>Weitere Hummeln bevorzugen<strong> Baumh\u00f6hlen, Dachisolierung und leere Vogelh\u00e4uschen<\/strong>, wie zum Beispiel die Baumhummel (Bombus hypnorum), oder<a href=\"https:\/\/www.cmelaciplus.cz\/de\/hummel-katalog-der-hummelarten-hummel-wiesenhumm-melicus-bombus-pratorum\/\" target=\"_blank\" rel=\"noopener\"> Wiesenhummel (Bombus pratorum)<\/a>.<\/p><p><strong>3. An der Oberfl\u00e4che und knapp darunter<\/strong><\/p><p>Einige Arten k\u00f6nnen sowohl unter als auch \u00fcber der Erde leben. Ein Beispiel daf\u00fcr ist die Gartenhummel (Bombus hortorum) oder <a href=\"https:\/\/www.cmelaciplus.cz\/de\/hummelartenkatalog-hummel-feldhummel-bombus-pascuorum\/\" target=\"_blank\" rel=\"noopener\">Ackerhummel (Bombus pascuorum)<\/a>.<\/p><p>Nat\u00fcrlich kann es eine Reihe von Ausnahmen geben, siehe zum Beispiel das Nest von Hummeln auf einem Nistkasten im Video.<\/p><p>Die H\u00f6hlung muss au\u00dferdem enthalten <strong>ausreichende W\u00e4rmed\u00e4mmung <\/strong>(z.B. Maus-\/Vogelnester), es darf kein<strong> Durchzug<\/strong> a <strong>darf nicht hineinlecken<\/strong>.<\/p><p>Mutter muss all dies untersuchen und abw\u00e4gen \u2013 allein und im Dunkeln. Sie muss auch untersuchen <b>w\u00e4rmed\u00e4mmende Eigenschaften <\/b>Dutiny.<\/p><p>Wir haben bisher keine geeignete Literatur dazu gefunden, aber wir vermuten, dass es \u00e4hnliche Methoden wie bei Bienen anwenden wird (obwohl dies dort von einer Gruppe von Arbeiterinnen durchgef\u00fchrt wird). Es wird die H\u00f6hle durchsuchen, <strong>erforschen<\/strong> Ich <strong>Ich rieche<\/strong> einen Tastendruck <strong>tykadly<\/strong>. Sie wird auch mit den Fl\u00fcgeln schlagen, mit denen \u201e<strong>misst die Gr\u00f6\u00dfe der Kavit\u00e4t<\/strong>\u201cIhre Bedeutung haben sicherlich auch die summenden Ger\u00e4usche, die die K\u00f6nigin w\u00e4hrend der Erkundung der H\u00f6hle von sich gibt. \u00a0<\/p><p>Einen Blick in ein Nest, das die Mutter untersucht, finden Sie im n\u00e4chsten Text.<\/p><p>Wie ein Schreck aussehen soll und welche K\u00f6niginnenm\u00fctter wir akzeptieren, beschreiben wir in unseren Anleitungen, zum Beispiel auf der Seite\u00a0<a href=\"https:\/\/www.cmelaciplus.cz\/de\/vorbereitung-der-boote-vor-der-saison\/\" target=\"_blank\" rel=\"noopener\"> Vorbereitung des Magens vor der Saison<\/a>.<\/p><p><strong><em>Interessant<\/em><\/strong><\/p><ul><li><em>Manchmal ist es f\u00fcr eine Mutter nicht entscheidend, ob die H\u00f6hle leer ist oder nicht. <\/em><em>Wenn nicht anders m\u00f6glich, kann die K\u00f6nigin die urspr\u00fcngliche Besitzerin (Maus, kleiner Vogel) vertreiben \u2013 eine solche Kampfbereitschaft ist bei der Hummelsorte Bombus hypnorum recht h\u00e4ufig.<\/em><\/li><li><em>Falls notwendig, k\u00e4mpft die K\u00f6nigin um eine Nistkammer, sogar mit anderen Hummeln und sogar mit ihren Schwestern \u2013 siehe nachfolgender Text)<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb1e7c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb1e7c2\" data-element_type=\"section\" data-e-type=\"section\" id=\"#\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c04c6b2\" data-id=\"c04c6b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-947938d elementor-widget elementor-widget-text-editor\" data-id=\"947938d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_1498\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1498\" class=\"wp-image-1498\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/3494815_.jpg\" alt=\"Hummel PLUS - Hummelnest in einer Erdh\u00f6hle\" width=\"350\" height=\"258\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/3494815_.jpg 750w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/3494815_-300x221.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-1498\" class=\"wp-caption-text\">Hummelnest in einer Nagetierh\u00f6hle Fotostock<\/p><\/div><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aadbf50\" data-id=\"aadbf50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbc78f2 elementor-widget elementor-widget-text-editor\" data-id=\"dbc78f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4666\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4666\" class=\"wp-image-4666\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/bumblebees_ground-Capoital-region-Beekepors-Associations.jpg\" alt=\"Hummel PLUS - Hummelnest von Bombus pascuorum in einem Gras Haufen\" width=\"350\" height=\"263\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/bumblebees_ground-Capoital-region-Beekepors-Associations.jpg 640w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/bumblebees_ground-Capoital-region-Beekepors-Associations-300x225.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-4666\" class=\"wp-caption-text\">Hummelnest der Ackerhummel (Bombus pascuorum) in einem Grassoden<br \/>Foto Internet<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b48a4c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b48a4c0\" data-element_type=\"section\" data-e-type=\"section\" id=\"#\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8184601\" data-id=\"8184601\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34680a1 elementor-widget elementor-widget-text-editor\" data-id=\"34680a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4670\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4670\" class=\"wp-image-4670\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_The_Peace_Bee_Farmer.jpg\" alt=\"Hummeln PLUS - Wespenspaziergang (Bombus hypnorum) in einem Vogelhaus\" width=\"350\" height=\"280\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_The_Peace_Bee_Farmer.jpg 1080w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_The_Peace_Bee_Farmer-300x240.jpg 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_The_Peace_Bee_Farmer-1024x819.jpg 1024w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_The_Peace_Bee_Farmer-768x614.jpg 768w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-4670\" class=\"wp-caption-text\">Hummelnest der Birkenhummel (Bombus hypnorum) in einem Nistkasten<br \/>Foto Der Friedensimker<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-02d9526\" data-id=\"02d9526\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dab2597 elementor-widget elementor-widget-text-editor\" data-id=\"dab2597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4668\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4668\" class=\"wp-image-4668\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_HnIzdo_cmelaku_rokytovych__Bombus_hypnorum_ptaci_budka_Sandy_Bedfordshire-scaled-e1581808454566.jpg\" alt=\"Hummeln PLUS - Nest von Stein-Hummeln (Bombus hypnorum) in einem Nistkasten\" width=\"350\" height=\"350\" \/><p id=\"caption-attachment-4668\" class=\"wp-caption-text\">Hummelnest von Bombus hypnorum in einem Nistkasten<br \/>Foto Jesus College Naturpfad<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4cfb7ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cfb7ef\" data-element_type=\"section\" data-e-type=\"section\" id=\"#\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d14a3c\" data-id=\"9d14a3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568be66 elementor-widget elementor-widget-text-editor\" data-id=\"568be66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4667\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4667\" class=\"wp-image-4667\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokyovych_jesus_collega_nature_trail.jpg\" alt=\"Hummeln PLUS - Ein Nest der Baumhummel (Bombus hypnorum) in einem Vogelnest in einem Baumloch \" width=\"350\" height=\"263\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokyovych_jesus_collega_nature_trail.jpg 480w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokyovych_jesus_collega_nature_trail-300x225.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-4667\" class=\"wp-caption-text\">Hummelnest des Felsenhummel (Bombus hypnorum)<br \/>Foto Jesus College Naturpfad<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e036266\" data-id=\"e036266\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00b6198 elementor-widget elementor-widget-text-editor\" data-id=\"00b6198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4673\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4673\" class=\"wp-image-4673\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-scaled.jpg\" alt=\"Hummeln PLUS - Hummelnest von Bombus hypnorum in einem Vogelhaus\" width=\"300\" height=\"401\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-scaled.jpg 1438w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-225x300.jpg 225w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-767x1024.jpg 767w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-768x1025.jpg 768w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-1151x1536.jpg 1151w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-1232x1645.jpg 1232w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-809x1080.jpg 809w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_rokytovych_Bombus_hypnorum_v_ptaci_budce_Dave_Jones-1320x1762.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-4673\" class=\"wp-caption-text\">Hummelnest der Felsenhummel (Bombus hypnorum) in einem Vogelhaus<br \/>Foto: Dave Jones<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c446e75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c446e75\" data-element_type=\"section\" data-e-type=\"section\" id=\"#\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18a060c\" data-id=\"18a060c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-644e733 elementor-widget elementor-widget-text-editor\" data-id=\"644e733\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4669\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4669\" class=\"wp-image-4669\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_skalnic_A_FRENCH_GARDEN.jpg\" alt=\"Hummel PLUS \u2013 Steinhummelnest (Bombus Lapidarius) in einer Mauer\" width=\"350\" height=\"229\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_skalnic_A_FRENCH_GARDEN.jpg 611w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_skalnic_A_FRENCH_GARDEN-300x196.jpg 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-4669\" class=\"wp-caption-text\">Hummeln PLUS \u2013 Ein Steinhummelnest (Bombus Lapidarius) in einer Mauer<br \/>Foto Ein Franz\u00f6sischer Garten<\/p><\/div><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e7a4947\" data-id=\"e7a4947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff96e2e elementor-widget elementor-widget-text-editor\" data-id=\"ff96e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"attachment_4699\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4699\" class=\"wp-image-4699\" src=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_zemnich_Bombus_tererstris_MS_Knezeves_u_Prahy.png\" alt=\"Hummel PLUS - Ein Nest von Erdhummeln (Bombus terrestris) im Kindergarten Kn\u011b\u017eeves bei Prag\" width=\"350\" height=\"234\" srcset=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_zemnich_Bombus_tererstris_MS_Knezeves_u_Prahy.png 946w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_zemnich_Bombus_tererstris_MS_Knezeves_u_Prahy-300x201.png 300w, https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Hnizdo_cmelaku_zemnich_Bombus_tererstris_MS_Knezeves_u_Prahy-768x514.png 768w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><p id=\"caption-attachment-4699\" class=\"wp-caption-text\">Einstiege in das Nest von Erdhummeln (Bombus terrestris) im Kindergarten Kn\u011b\u017eeves bei Prag<br \/>Foto O. Hercog<\/p><\/div><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-cab640c elementor-widget elementor-widget-video\" data-id=\"cab640c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Mn7mb2VqG1E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8114eb elementor-widget elementor-widget-text-editor\" data-id=\"a8114eb\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"#\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein ziemlich einzigartiges Video von V\u00edt Cacho. Er hat eine ungew\u00f6hnliche Situation festgehalten, in der ein Weibchen der Erdhummel (Bombus terrestris) trockenes Moos in eine Nistkugel tr\u00e4gt. Die meisten Hummelarten tun dies nicht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c18fb18 elementor-widget elementor-widget-video\" data-id=\"c18fb18\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/zrAcpqJtZ9g&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e61fad elementor-widget elementor-widget-video\" data-id=\"8e61fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/uQa5szhhMO0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db16a86 elementor-widget elementor-widget-text-editor\" data-id=\"db16a86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ausnahmen best\u00e4tigen die Regel \u2013 hier haben sich Hummeln (Bombus terrestris) in einem Vogelhaus eingenistet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d56c14a elementor-widget elementor-widget-video\" data-id=\"d56c14a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/LFuc-N5xYbg&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67db22c elementor-widget elementor-widget-text-editor\" data-id=\"67db22c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"4\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Wie erkennt man eine Mutter, die einen Nistplatz sucht?<\/strong><\/h4><p>Eine suchende Mutterk\u00f6nigin erkennt man leicht, vor allem an ihrer typischen <strong>Suchflug<\/strong> niedrig \u00fcber dem Boden.<\/p><p>Er sitzt nicht auf Bl\u00fcten und geht uninteressiert an ihnen vorbei. Er kriecht in Erdh\u00f6hlen oder verschiedene \u00d6ffnungen und verl\u00e4sst sie wieder. Er sucht darin Hohlr\u00e4ume, um sich niederzulassen. In einigen bleibt er und untersucht sie, andere verl\u00e4sst er sofort.<\/p><p>M\u00fctter aktiv <b>suchen w\u00e4hrend mehrerer Wellen nach Brutgebieten<\/b> \u2013 vormittags und sp\u00e4ter am Nachmittag in 1-2 Wellen. Insbesondere <b>Interessant ist f\u00fcr sie der Abend.<\/b>, wenn sich der Wind beruhigt und sie f\u00fcr den Flug nicht so viel Energie ben\u00f6tigen.<br \/>Wenn es kalt oder windig ist, sind sie bei der Jagd nicht so aktiv. Ebenso sind sie nicht sehr aktiv, wenn sie Wetter\u00e4nderungen sp\u00fcren und die Bedingungen zum Nisten ung\u00fcnstig werden (Temperatur und Nahrungsmenge).\u00a0<br \/>Dies sind allgemeine Regeln, aber Sie k\u00f6nnen durchaus eine K\u00f6nigin treffen, die auch zur Mittagszeit nach einem Nistplatz sucht.<\/p><p>Mutter <strong>sucht dunkle Fl\u00e4chen<\/strong> \u2013 L\u00f6cher im Boden, L\u00f6cher in der Wand, Eing\u00e4nge zu Vogelh\u00e4usern, Risse in der Wand.<\/p><p>Es ist ein sehr typischer Flug und kann nicht verwechselt werden. Auch der Flug der M\u00e4nnchen, die in der fortgeschrittenen Jahreszeit nach Weibchen zur Paarung suchen, sieht anders aus und Arbeiterinnen fliegen niemals so. Au\u00dferdem findet man Arbeiterinnen oder M\u00e4nnchen im Fr\u00fchling nicht in der freien Natur. Die K\u00f6nigin benutzt diesen Flug nur, wenn sie nach einem Nistplatz sucht.<\/p><p><strong><em>Interessant<\/em><\/strong><\/p><ul><li><em>Mutter werden<strong> suchen nur bei sch\u00f6nem Wetter<\/strong>Und wenn sie keinen Hunger haben und nach Nahrung suchen \u2013 hungrig geht das nicht\u2026.<\/em><\/li><li><em>Sie suchen also sehr oft am Vormittag und sp\u00e4ter am Nachmittag, wenn kein starker Wind weht und der Suchflug sie nicht viel Energie kostet<\/em><\/li><li><em>Manchmal <strong>Die F\u00fctterungsphase nach dem Winter und die Suche k\u00f6nnen sich \u00fcberschneiden.<\/strong>. Die K\u00f6niginmutter erkundet also das Gel\u00e4nde und n\u00e4hert sich Schritt f\u00fcr Schritt interessanten Orten. <strong>bringt zur\u00fcck<\/strong>, <strong>wenn die richtige Zeit zum Nisten gekommen ist<\/strong>.<\/em><\/li><li><em>Die Suche nach dem Nest kann dauern<strong> einige Wochen<\/strong>. Solange die Mutter keinen Ort findet, der ihr zusagt, wird sie sich nicht niederlassen, weil sie wei\u00df, dass es sich nicht lohnen w\u00fcrde.<\/em><\/li><li><em>Mutter manchmal Suche selbst <strong>unterbrechen<\/strong>, z.B. wenn es stark abk\u00fchlt. Wenn sonst alles in Ordnung ist, wird sp\u00e4ter mit der Suche fortgefahren\u00a0<\/em><\/li><li><em>Wenn die Mutter rechtzeitig keinen geeigneten Nistplatz findet oder ihr bereits angelegtes Nest verliert, wird sie zu einer sogenannten <b>Irrlicht<\/b>. <br \/>Sie wird nach einem Nistplatz Ausschau halten, aber ihr Nestbautrieb wird nachlassen und<strong> wird nie wieder ein Nest bauen<\/strong>. Eine solche Mutter kann von einem Ergreifer immer wieder in den Stock gef\u00fchrt werden, aber sie wird sich dort nicht ansiedeln.<\/em><\/li><\/ul><div><p><strong>Bitte schauen Sie sich die Videos an, die typische Suchfl\u00fcge von M\u00fcttern zeigen. <\/strong><strong>Wenn Sie keinen solchen Flug sehen, hat es keinen Sinn, die Mutter zu \u00fcberreden, sich einzuleben.<\/strong><br \/><i><\/i><\/p><p>\u00a0<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce438f9 elementor-widget elementor-widget-video\" data-id=\"ce438f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/kTcD28bq5uA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2802ed6 elementor-widget elementor-widget-video\" data-id=\"2802ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/pJnPzkkzlEk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f76c042 elementor-widget elementor-widget-video\" data-id=\"f76c042\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/a7-wisJAUBw&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb0e1d5 elementor-widget elementor-widget-video\" data-id=\"bb0e1d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/JRruboFzsNU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed194f1 elementor-widget elementor-widget-text-editor\" data-id=\"ed194f1\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"5\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Wenn eine Mutter nach einem Nistplatz sucht, br\u00fctet sie dort dann immer?<\/strong><\/h4><p>Manchmal mit dem Nestbau <b>muss warten,<\/b> weil es kalt und wenig Nahrung gibt. Daher sucht sie sich oft einen geeigneten Ort und kehrt dorthin zur\u00fcck, wenn die Zeit reif ist.<\/p><p>Es kann Ihnen also passieren, dass Sie einer solchen Mutter einen Schreck anbieten und sie ihn nicht annimmt \u2013 sie will es einfach noch nicht und Sie werden sie nicht \u00fcberzeugen.<\/p><p>versuche, eine Mutter aus dir zu machen <b>Irrlicht<\/b>, wird auch gelegentlich Suchfl\u00fcge unternehmen, aber nicht br\u00fcten. Manchmal werden solche <strong>Bludi\u010dky napadaj\u00ed hn\u00edzda jin\u00fdch matek sv\u00e9ho druhu. <\/strong>\u2013 versucht, das Nest zu \u00fcbernehmen. <br \/>Wir erkl\u00e4ren uns das so, dass <strong>Eine Mutter, die ihr Nest verloren hat, hat nicht mehr genug Energie, um bei Null anzufangen.<\/strong> Also geht er ein Risiko ein und versucht, ein anderes Nest zu \u00fcbernehmen.<\/p><p>Z\u00fcchter nutzen diesen Effekt manchmal aus, indem sie einer solchen K\u00f6nigin einen Bienenstock anbieten, der aus irgendeinem Grund seine K\u00f6nigin verloren hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a1495 elementor-widget elementor-widget-video\" data-id=\"29a1495\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/c36lyViIZHI&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d3939 elementor-widget elementor-widget-text-editor\" data-id=\"e2d3939\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"6\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Wie unterscheidet man eine Mutter, die ein Nest sucht, von einer, die keins sucht?<\/strong><\/h4><p>Wenn die Mutter <b>p<\/b><strong>f\u00fchrt einen Suchflug <span style=\"color: #339966;\">sucht Brutpl\u00e4tze<\/span><\/strong>. Hat es einen Wert, sie zu erschrecken.<\/p><p>Wenn die K\u00f6nigin-Mutter <strong>frisst an Bl\u00fcten<\/strong>, oder<strong>und in der H\u00f6he<\/strong> ja <strong><span style=\"color: #ff0000;\">sucht keine Nistpl\u00e4tze<\/span><\/strong>, e, oder es ist nicht bestimmbar. Sicherlich ihr aber <span style=\"color: #ff0000;\"><strong>Es hat keinen Sinn, einen Schreck anzubieten \u2013 er wird ihn nicht annehmen.<\/strong><\/span>.<\/p><p>Wenn die Mutter <strong>an den Hinterbeinen Pollenh\u00f6schen<\/strong> so nun <span style=\"color: #ff0000;\"><strong>Sie hat ein eigenes Nest und Sie d\u00fcrfen sie nicht st\u00f6ren<\/strong><\/span>. Das angebotene Nest w\u00fcrde sie auf keinen Fall annehmen und im Falle eines Unfalls w\u00fcrde ihr verlassener Nachwuchs sterben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a692ad2 elementor-widget elementor-widget-text-editor\" data-id=\"a692ad2\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"7\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Was passiert, wenn sich mehrere M\u00fctter an einem geeigneten Nistplatz treffen?<\/strong><\/h4><p>Das passiert leider. Hier dann <strong>Das Recht des St\u00e4rkeren siegt.<\/strong> M\u00fctter tragen untereinander aus <b>Kampf <\/b>und die St\u00e4rkste gewinnt. Es ist ein Kampf auf Leben und Tod und endet oft mit Verletzungen und dem Tod beider M\u00fctter.\u00a0<\/p><p>Ebenso kann es vorkommen, dass eine von einer fr\u00fchen Hummelart besetzte H\u00f6hle von einer sp\u00e4teren, kr\u00e4ftigeren Art besiedelt werden will. Es wurde beobachtet <strong>Koexistenz<\/strong> zwei <strong>mehrere K\u00f6niginnen in einem Bienenstock<\/strong>, aber nur vor\u00fcbergehend. Auch dort kam es schlie\u00dflich zu einem Kampf.<\/p><p><strong>Beim Z\u00fcchten von Hummeln kann dies verhindert werden<\/strong> damit der Z\u00fcchter die etablierte K\u00f6nigin rechtzeitig daran gew\u00f6hnt, durch die Klappe zu gehen (ge\u00f6ffnete Klappe), und sp\u00e4tere Ank\u00f6mmlinge so nicht in die H\u00f6hle gelangen.<\/p><p>Die M\u00fctter der meisten Arten verlassen sich zuverl\u00e4ssig <strong>keim zur\u00fcck an den Ort der Geburtsst\u00e4tte<\/strong> (sofern sie die Winterstarre \u00fcberleben). Dann liefern sich die Schwestern dort einen Kampf um das Nistrevier. <br \/>Der Kampf ist z\u00e4h \u2013 die M\u00fctter k\u00e4mpfen um die H\u00f6hle, die es ihnen erm\u00f6glicht hat und Hummeln hier ihren Zyklus beendet haben, also werden sie es noch einmal versuchen.<\/p><p>Zur L\u00f6sung der Situation, <strong>wann kehren die M\u00fctter in das Brutnest des Z\u00fcchters zur\u00fcck<\/strong>, lesen Sie auf der Seite\u00a0 <a href=\"https:\/\/www.cmelaciplus.cz\/de\/heimkehr-der-mutter-ins-heimatland\/\" target=\"_blank\" rel=\"noopener\">R\u00fcckkehr der M\u00fctter zum Stock \u2013 dem Geburtsnest.<\/a><\/p><p><strong><em>Interessant<\/em><\/strong><\/p><ul><li><em>Manchmal ist der Z\u00fcchter \u00fcberrascht, wenn er in einem Bienenstock eine K\u00f6nigin mit Brut und eine tote K\u00f6nigin findet. Anscheinend kam es hier zu einem Kampf.<\/em><\/li><li><em>M\u00fctter k\u00f6nnen sich im Kampf leider gegenseitig verletzen und beide sterben.<\/em><\/li><li><em>In der Natur gibt es einen Ort, an dem es mehr tote M\u00fctter als erfolgreich br\u00fctende gibt (Beobachtung von J. \u010c\u00ed\u017eek).<\/em><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62c5bde elementor-widget elementor-widget-text-editor\" data-id=\"62c5bde\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"8\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>Brauchen M\u00fctter im Fr\u00fchling Hilfe \u2013 wann ja und wenn ja, welche?<\/strong><\/h4><p>Die K\u00f6niginnen sind f\u00fcr die T\u00fccken des Fr\u00fchlings gewappnet \u2013 Temperaturschwankungen, Niederschlag und Nahrungsmangel. Manchmal kommt es jedoch vor, dass man eine ersch\u00f6pfte K\u00f6nigin in der Natur findet und abw\u00e4gt, ob und wie man ihr helfen kann.\u00a0<\/p><p>Unsere Seite hilft Ihnen bei Entscheidungen und m\u00f6glichen Ma\u00dfnahmen <a href=\"https:\/\/www.cmelaciplus.cz\/de\/hilfe-die-hornissen-sind-im-fruhling\/\" target=\"_blank\" rel=\"noopener\">Hilfe f\u00fcr Hummeln im Fr\u00fchling<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5e05fe elementor-widget elementor-widget-video\" data-id=\"f5e05fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/_TKtyO8-WTA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jak odli\u0161it ji\u017e zabydlen\u00e9ho \u010dmel\u00e1ka od hledaj\u00edc\u00ed matky Co se zde dozv\u00edte Co d\u011bl\u00e1 \u010dmel\u00e1\u010d\u00ed matka po probuzen\u00ed Jak hled\u00e1 m\u00edsto k zahn\u00edzd\u011bn\u00ed &#8211; hn\u00edzdi\u0161t\u011b Jak takovou matku spolehliv\u011b poznat Pro\u010d se matky n\u011bkdy nezahn\u00edzd\u00ed, i kdy\u017e hledaj\u00ed hn\u00edzdi\u0161t\u011b Datum posledn\u00ed aktualizace: 23\/2\/2024 Matky-kr\u00e1lovny \u010dmel\u00e1k\u016f se probouz\u00ed: matky se probouz\u00ed postupn\u011b, nejprve ran\u00e9 druhy &#8211;&nbsp;&hellip;<\/p>","protected":false},"author":3,"featured_media":4705,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"wf_page_folders":[23],"class_list":["post-4651","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Matka hled\u00e1 hn\u00edzdi\u0161t\u011b &#8211; \u010cmel\u00e1ci PLUS<\/title>\n<meta name=\"description\" content=\"\u010cmel\u00e1k na ja\u0159e to je \u010dmel\u00e1\u010d\u00ed kr\u00e1lovna. Co d\u011bl\u00e1 po probuzen\u00ed, jak si hled\u00e1 nov\u00e9 hn\u00edzdi\u0161t\u011b. Jak poznat matku, kter\u00e1 hled\u00e1 a kter\u00e1 ji\u017e hn\u00edzdo m\u00e1\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cmelaciplus.cz\/de\/mutter-sucht-brutstatte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matka hled\u00e1 hn\u00edzdi\u0161t\u011b &#8211; \u010cmel\u00e1ci PLUS\" \/>\n<meta property=\"og:description\" content=\"\u010cmel\u00e1k na ja\u0159e to je \u010dmel\u00e1\u010d\u00ed kr\u00e1lovna. Co d\u011bl\u00e1 po probuzen\u00ed, jak si hled\u00e1 nov\u00e9 hn\u00edzdi\u0161t\u011b. Jak poznat matku, kter\u00e1 hled\u00e1 a kter\u00e1 ji\u017e hn\u00edzdo m\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cmelaciplus.cz\/de\/mutter-sucht-brutstatte\/\" \/>\n<meta property=\"og:site_name\" content=\"\u010cmel\u00e1ci PLUS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cmelaciplus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T22:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cmelaci\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"18\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/\",\"name\":\"Matka hled\u00e1 hn\u00edzdi\u0161t\u011b &#8211; \u010cmel\u00e1ci PLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg\",\"datePublished\":\"2020-02-15T21:58:49+00:00\",\"dateModified\":\"2026-05-09T22:00:55+00:00\",\"description\":\"\u010cmel\u00e1k na ja\u0159e to je \u010dmel\u00e1\u010d\u00ed kr\u00e1lovna. Co d\u011bl\u00e1 po probuzen\u00ed, jak si hled\u00e1 nov\u00e9 hn\u00edzdi\u0161t\u011b. Jak poznat matku, kter\u00e1 hled\u00e1 a kter\u00e1 ji\u017e hn\u00edzdo m\u00e1\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"Matka \u010dmel\u00e1ka zemn\u00edho (Bombus_terrestris) hled\u00e1 hn\u00edzdi\u0161te Foto Flicker\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/matka-hleda-hnizdiste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matka hled\u00e1 hn\u00edzdi\u0161t\u011b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#website\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\",\"name\":\"\u010cmel\u00e1ci PLUS\",\"description\":\"\u010cmel\u00e1ci PLUS Pom\u00e1h\u00e1me \u010dmel\u00e1k\u016fm a p\u0159\u00edrod\u011b -  Unik\u00e1tn\u00ed encyklopedie \u010dmel\u00e1k\u016f\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#organization\",\"name\":\"\u010cmel\u00e1ci PLUS z.s.\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png\",\"contentUrl\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png\",\"width\":50,\"height\":50,\"caption\":\"\u010cmel\u00e1ci PLUS z.s.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cmelaciplus.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cmelaciplus\",\"https:\\\/\\\/x.com\\\/cmelaci\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHMo-5xkRu3J-vM9UVzOl9Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die K\u00f6nigin sucht eine Nistst\u00e4tte \u2013 Hummeln PLUS","description":"Im Fr\u00fchling ist ein Hummel eine Hummelk\u00f6nigin. Was sie nach dem Aufwachen tut, wie sie ein neues Nest sucht. Wie man eine K\u00f6nigin erkennt, die sucht, und eine, die bereits ein Nest hat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cmelaciplus.cz\/de\/mutter-sucht-brutstatte\/","og_locale":"de_DE","og_type":"article","og_title":"Matka hled\u00e1 hn\u00edzdi\u0161t\u011b &#8211; \u010cmel\u00e1ci PLUS","og_description":"\u010cmel\u00e1k na ja\u0159e to je \u010dmel\u00e1\u010d\u00ed kr\u00e1lovna. Co d\u011bl\u00e1 po probuzen\u00ed, jak si hled\u00e1 nov\u00e9 hn\u00edzdi\u0161t\u011b. Jak poznat matku, kter\u00e1 hled\u00e1 a kter\u00e1 ji\u017e hn\u00edzdo m\u00e1","og_url":"https:\/\/www.cmelaciplus.cz\/de\/mutter-sucht-brutstatte\/","og_site_name":"\u010cmel\u00e1ci PLUS","article_publisher":"https:\/\/www.facebook.com\/cmelaciplus","article_modified_time":"2026-05-09T22:00:55+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cmelaci","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"18\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/","url":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/","name":"Die K\u00f6nigin sucht eine Nistst\u00e4tte \u2013 Hummeln PLUS","isPartOf":{"@id":"https:\/\/www.cmelaciplus.cz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/#primaryimage"},"image":{"@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg","datePublished":"2020-02-15T21:58:49+00:00","dateModified":"2026-05-09T22:00:55+00:00","description":"Im Fr\u00fchling ist ein Hummel eine Hummelk\u00f6nigin. Was sie nach dem Aufwachen tut, wie sie ein neues Nest sucht. Wie man eine K\u00f6nigin erkennt, die sucht, und eine, die bereits ein Nest hat.","breadcrumb":{"@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/#primaryimage","url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg","contentUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2020\/02\/Cmelaci_PLUS_Matka_cmelaka_zemniho_Bombus_terrestris_hleda_hnizdiste_Flisker.jpg","width":1024,"height":1024,"caption":"Matka \u010dmel\u00e1ka zemn\u00edho (Bombus_terrestris) hled\u00e1 hn\u00edzdi\u0161te Foto Flicker"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cmelaciplus.cz\/matka-hleda-hnizdiste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.cmelaciplus.cz\/"},{"@type":"ListItem","position":2,"name":"Matka hled\u00e1 hn\u00edzdi\u0161t\u011b"}]},{"@type":"WebSite","@id":"https:\/\/www.cmelaciplus.cz\/#website","url":"https:\/\/www.cmelaciplus.cz\/","name":"Hummeln PLUS","description":"Hummel PLUS Wir helfen Hummeln und der Natur \u2013 Einzigartige Hummel-Enzyklop\u00e4die","publisher":{"@id":"https:\/\/www.cmelaciplus.cz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cmelaciplus.cz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cmelaciplus.cz\/#organization","name":"Hummeln PLUS e.V.","url":"https:\/\/www.cmelaciplus.cz\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cmelaciplus.cz\/#\/schema\/logo\/image\/","url":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png","contentUrl":"https:\/\/www.cmelaciplus.cz\/wp-content\/uploads\/2019\/11\/cropped-cropped-CMELACI_PLUS_LOGO-removebg-preview-e1776883782982.png","width":50,"height":50,"caption":"\u010cmel\u00e1ci PLUS z.s."},"image":{"@id":"https:\/\/www.cmelaciplus.cz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cmelaciplus","https:\/\/x.com\/cmelaci","https:\/\/www.youtube.com\/channel\/UCHMo-5xkRu3J-vM9UVzOl9Q"]}]}},"_links":{"self":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/4651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/comments?post=4651"}],"version-history":[{"count":247,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/4651\/revisions"}],"predecessor-version":[{"id":37944,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/pages\/4651\/revisions\/37944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/media\/4705"}],"wp:attachment":[{"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/media?parent=4651"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.cmelaciplus.cz\/de\/wp-json\/wp\/v2\/wf_page_folders?post=4651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}